{"id":1027,"date":"2018-11-14T02:28:43","date_gmt":"2018-11-14T02:28:43","guid":{"rendered":"http:\/\/www.charcoal-machines.com\/?p=1027"},"modified":"2024-09-19T16:38:21","modified_gmt":"2024-09-19T08:38:21","slug":"the-so-called-continuous-carbonization-machine-is-common-in-the-market","status":"publish","type":"post","link":"https:\/\/www.charcoal-machines.com\/pt\/the-so-called-continuous-carbonization-machine-is-common-in-the-market.html","title":{"rendered":"A chamada m\u00e1quina de carboniza\u00e7\u00e3o cont\u00ednua \u00e9 comum no mercado."},"content":{"rendered":"<p>As m\u00e1quinas de carboniza\u00e7\u00e3o cont\u00ednua est\u00e3o na ind\u00fastria de produ\u00e7\u00e3o de carv\u00e3o vegetal dom\u00e9stico h\u00e1 muito tempo. Por que a forma sem carbono do mecanismo do carv\u00e3o \u00e9 amplamente conhecida? Se uma m\u00e1quina comercial colocada no mercado n\u00e3o \u00e9 amplamente reconhecida, ent\u00e3o naturalmente n\u00e3o ser\u00e1 conhecida pelo p\u00fablico. A chamada m\u00e1quina de carboniza\u00e7\u00e3o cont\u00ednua no mercado \u00e9 a mesma coisa.<\/p> <p class=\"translation-block\">A chamada <strong>m\u00e1quina de carboniza\u00e7\u00e3o<\/strong> cont\u00ednua comumente usada no mercado \u00e9 apenas um tipo de equipamento de secagem do tipo tambor rotativo. Depois que a empresa de maquinaria de pequena oficina aprimorou cuidadosamente a vers\u00e3o de temperatura elevada do equipamento mec\u00e2nico, ela n\u00e3o pode ser chamada de equipamento de carboniza\u00e7\u00e3o, nem mesmo de maturidade t\u00e9cnica. Equipamento mec\u00e2nico, hoje apresenta o problema de defeitos de temperatura.<\/p> <p>\u00c9 bem conhecido que a maioria dos materiais utilizados em equipamentos mec\u00e2nicos s\u00e3o feitos de a\u00e7o, e as m\u00e1quinas de acionamento rotativo do tipo tambor n\u00e3o s\u00e3o exce\u00e7\u00e3o. Qual \u00e9 o princ\u00edpio de funcionamento comum da chamada m\u00e1quina de carboniza\u00e7\u00e3o cont\u00ednua no mercado? O material \u00e9 virado em um cilindro de material de a\u00e7o com uma certa espessura, e a parede externa da chapa de a\u00e7o \u00e9 aquecida por uma chama de fonte de calor, e a chapa de a\u00e7o \u00e9 condutora de calor, alcan\u00e7ando assim o objetivo de aquecer indiretamente o material. O problema \u00e9 que o que precisamos \u00e9 de carboniza\u00e7\u00e3o em estado anaer\u00f3bico. No tambor de a\u00e7o, o estado livre de oxig\u00eanio pode ser alcan\u00e7ado, mas que tipo de estado pode fazer a temperatura subir?<\/p> <p><center><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-138\" src=\"http:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2018\/08\/carbonization-furnace4.jpg\" alt=\"forno de carboniza\u00e7\u00e3o\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2018\/08\/carbonization-furnace4.jpg 600w, https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2018\/08\/carbonization-furnace4-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/center>Voc\u00ea pode pesquisar a temperatura de amolecimento do a\u00e7o no motor de busca e pode chegar \u00e0 resposta sem mais explora\u00e7\u00e3o: 500 graus Celsius. Ao olhar os dados para uma pesquisa detalhada, voc\u00ea descobrir\u00e1 que 500 graus Celsius \u00e9 apenas a temperatura de amolecimento em laborat\u00f3rio dada pelo material da chapa de a\u00e7o produzido pela grande sider\u00fargica. A chapa de a\u00e7o comumente usada no mercado n\u00e3o atinge tal temperatura de amolecimento. Ent\u00e3o, qual \u00e9 a temperatura de uso espec\u00edfica da chapa de a\u00e7o comum?<\/p> <p>A temperatura do Q235-B chega a 350 \u00b0C! A maioria das chapas de a\u00e7o comuns no mercado \u00e9 Q235-C, e a temperatura de uso \u00e9 mais baixa.<br \/> Falando sobre isso, todos devem ter algumas percep\u00e7\u00f5es. A chamada m\u00e1quina de carboniza\u00e7\u00e3o cont\u00ednua \u00e9 comum no mercado:<\/p> <p class=\"translation-block\">A exig\u00eancia de temperatura para carbonizar mat\u00e9rias-primas de madeira \u00e9 de 435 \u00b0C (esta \u00e9 a menor classifica\u00e7\u00e3o de queima de carv\u00e3o sem fuma\u00e7a). Como essas empresas de pequena oficina fazem isso? A m\u00e1quina de carboniza\u00e7\u00e3o cont\u00ednua do tipo tambor feita de chapa de a\u00e7o \u00e9 submetida a uma temperatura de mais de 350 \u00b0C por um longo tempo sob o movimento rotativo de energia motriz, e a apar\u00eancia n\u00e3o \u00e9 deformada, e a m\u00e1quina n\u00e3o \u00e9 sucateada.<\/p>   <div class=\"kk-star-ratings kksr-auto kksr-align-right kksr-valign-bottom\"     data-payload='{&quot;align&quot;:&quot;right&quot;,&quot;id&quot;:&quot;1027&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;6&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.8&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.8\\\/5 - (6 votos)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;The so-called continuous carbonization machine is common in the market&quot;,&quot;width&quot;:&quot;132.4&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>              <div class=\"kksr-stars\">      <div class=\"kksr-stars-inactive\">             <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div>      <div class=\"kksr-stars-active\" style=\"width: 132.4px;\">             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div> <\/div>                   <div class=\"kksr-legend\" style=\"font-size: 19.2px;\">             4,8\/5 - (6 votos)    <\/div>     <\/div>","protected":false},"excerpt":{"rendered":"<p>As m\u00e1quinas de carboniza\u00e7\u00e3o cont\u00ednua est\u00e3o na ind\u00fastria de produ\u00e7\u00e3o de carv\u00e3o vegetal dom\u00e9stico h\u00e1 muito tempo. Por que a forma sem carbono do mecanismo do carv\u00e3o \u00e9 amplamente conhecida? Se uma m\u00e1quina comercial colocada no mercado n\u00e3o \u00e9 amplamente reconhecida, ent\u00e3o naturalmente n\u00e3o ser\u00e1 conhecida pelo p\u00fablico. O chamado cont\u00ednuo...<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[2],"tags":[46],"class_list":["post-1027","post","type-post","status-publish","format-standard","hentry","category-events","tag-carbonization-machine"],"taxonomy_info":{"category":[{"value":2,"label":"News"}],"post_tag":[{"value":46,"label":"carbonization machine"}]},"featured_image_src_large":false,"author_info":{"display_name":"Lolita","author_link":"https:\/\/www.charcoal-machines.com\/pt\/author\/admin"},"comment_info":0,"category_info":[{"term_id":2,"name":"News","slug":"events","term_group":0,"term_taxonomy_id":2,"taxonomy":"category","description":"","parent":0,"count":209,"filter":"raw","cat_ID":2,"category_count":209,"category_description":"","cat_name":"News","category_nicename":"events","category_parent":0}],"tag_info":[{"term_id":46,"name":"carbonization machine","slug":"carbonization-machine","term_group":0,"term_taxonomy_id":46,"taxonomy":"post_tag","description":"","parent":0,"count":7,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/www.charcoal-machines.com\/pt\/wp-json\/wp\/v2\/posts\/1027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charcoal-machines.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charcoal-machines.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/pt\/wp-json\/wp\/v2\/comments?post=1027"}],"version-history":[{"count":0,"href":"https:\/\/www.charcoal-machines.com\/pt\/wp-json\/wp\/v2\/posts\/1027\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.charcoal-machines.com\/pt\/wp-json\/wp\/v2\/media?parent=1027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/pt\/wp-json\/wp\/v2\/categories?post=1027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/pt\/wp-json\/wp\/v2\/tags?post=1027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}