{"id":1047,"date":"2018-11-19T06:51:27","date_gmt":"2018-11-19T06:51:27","guid":{"rendered":"http:\/\/www.charcoal-machines.com\/?p=1047"},"modified":"2019-05-27T03:15:59","modified_gmt":"2019-05-27T03:15:59","slug":"importance-of-control-of-coal-fired-heat-source-in-wood-chip-dryer","status":"publish","type":"post","link":"https:\/\/www.charcoal-machines.com\/fr\/importance-of-control-of-coal-fired-heat-source-in-wood-chip-dryer.html","title":{"rendered":"Importance du contr\u00f4le de la source de chaleur \u00e0 charbon dans le s\u00e9choir \u00e0 plaquettes de bois"},"content":{"rendered":"<p class=\"translation-block\">La soci\u00e9t\u00e9 d'aujourd'hui promeut la conservation de l'\u00e9nergie et la r\u00e9duction des \u00e9missions. En tant que fabricant engag\u00e9 dans la production et la fabrication d'\u00e9quipements de s\u00e9chage <strong><a href=\"https:\/\/www.charcoal-machines.com\/fr\/rotary-dryer.html\">s\u00e9choir<\/a> <\/strong>depuis de nombreuses ann\u00e9es, nous nous effor\u00e7ons constamment de produire des \u00e9quipements de s\u00e9chage plus \u00e9conomes en \u00e9nergie et plus respectueux de l'environnement. Le co\u00fbt d'utilisation de l'appareil est r\u00e9duit, et les revenus sont pour nos utilisateurs.<\/p> <p>Les s\u00e9choirs utilisent g\u00e9n\u00e9ralement le charbon comme source de chaleur. Pour r\u00e9duire le co\u00fbt de l'utilisation du charbon, il est n\u00e9cessaire de s'assurer que le charbon est enti\u00e8rement br\u00fbl\u00e9. Des facteurs tels que la taille du charbon, l'\u00e9paisseur du gisement de charbon et la quantit\u00e9 d'air souffl\u00e9 affectent la combustion compl\u00e8te du charbon.<\/p> <div class=\"col-md-6\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" class=\"alignnone size-full wp-image-169\" src=\"http:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2018\/08\/airflow-dryer2.jpg\" alt=\"s\u00e8che-air\" srcset=\"https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2018\/08\/airflow-dryer2.jpg 600w, https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2018\/08\/airflow-dryer2-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div> <h3>Contr\u00f4le de la source de chaleur au charbon dans le s\u00e9choir \u00e0 copeaux de bois<\/h3> <p>Tout d'abord, le charbon est l'une des sources de chaleur que nous connaissons le mieux. Si nous choisissons d'utiliser le charbon comme source de chaleur pour les s\u00e9choirs \u00e0 copeaux de bois, nous devons configurer le four \u00e0 air chaud aliment\u00e9 au charbon correspondant. Le charbon est utilis\u00e9 comme source de chaleur. Dans le processus de fonctionnement du s\u00e9choir \u00e0 copeaux de bois, l'effet du transfert de chaleur et de gaz sur le mat\u00e9riau est r\u00e9alis\u00e9 par la combustion du charbon, et finalement, la d\u00e9shydratation et le s\u00e9chage des copeaux de bois sont r\u00e9alis\u00e9s. En comparaison, les sources de chaleur au charbon sont un type courant dans les s\u00e9choirs \u00e0 copeaux de bois, mais une pollution de l'air peut se produire pendant l'utilisation.<\/p> <p>Deuxi\u00e8mement, afin d'assurer la propret\u00e9 de la production de d\u00e9shydratation des copeaux de bois, certains utilisateurs choisissent \u00e9galement d'utiliser l'\u00e9lectricit\u00e9 comme source de chaleur pour les s\u00e9choirs \u00e0 copeaux de bois. Bien s\u00fbr, si l'\u00e9lectricit\u00e9 est utilis\u00e9e comme source de chaleur, un chauffe-eau \u00e9lectrique est n\u00e9cessaire. La mani\u00e8re dont l'\u00e9lectricit\u00e9 est utilis\u00e9e comme source de chaleur consiste \u00e0 convertir l'\u00e9lectricit\u00e9 en \u00e9nergie thermique, et finalement \u00e0 r\u00e9aliser la d\u00e9shydratation et le s\u00e9chage des copeaux de bois. Dans des conditions normales, l'\u00e9quipement de d\u00e9shydratation a une tr\u00e8s haute efficacit\u00e9 thermique et un co\u00fbt relativement \u00e9lev\u00e9, et peut g\u00e9n\u00e9ralement atteindre plus de 10 fois le co\u00fbt des sources de chaleur \u00e0 base de charbon.<\/p> <p>Troisi\u00e8mement, ces derni\u00e8res ann\u00e9es, le gaz, le p\u00e9trole et autres comme source de chaleur pour les s\u00e9choirs \u00e0 copeaux de bois ont souvent \u00e9t\u00e9 choisis par les utilisateurs. Cependant, lors de l'utilisation de cette source de chaleur, il est important de pr\u00eater attention \u00e0 la s\u00e9curit\u00e9 du processus de transport. Bien que cette m\u00e9thode de source de chaleur ait une efficacit\u00e9 de d\u00e9shydratation et de s\u00e9chage plus \u00e9lev\u00e9e, le co\u00fbt est beaucoup plus \u00e9lev\u00e9 que celui de la combustion du charbon, il n'y a pas beaucoup d'utilisateurs qui choisissent cette m\u00e9thode de source de chaleur.<\/p> <p>Le s\u00e9chage des copeaux de bois est une sorte de production industrielle \u00e0 haute \u00e9nergie, et la r\u00e9duction efficace de la consommation de combustible peut r\u00e9duire efficacement la quantit\u00e9 de combustible utilis\u00e9e dans la production et diminuer l'utilisation globale \u00e0 faible consommation d'\u00e9nergie.<\/p>   <div class=\"kk-star-ratings kksr-auto kksr-align-right kksr-valign-bottom\"     data-payload='{&quot;align&quot;:&quot;right&quot;,&quot;id&quot;:&quot;1047&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;28&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.9&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.9\\\/5 - (28 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Importance of control of coal-fired heat source in wood chip dryer&quot;,&quot;width&quot;:&quot;135.2&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>              <div class=\"kksr-stars\">      <div class=\"kksr-stars-inactive\">             <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div>      <div class=\"kksr-stars-active\" style=\"width: 135.2px;\">             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div> <\/div>                   <div class=\"kksr-legend\" style=\"font-size: 19.2px;\">             4,9\/5 - (28 votes)    <\/div>     <\/div>","protected":false},"excerpt":{"rendered":"<p>La soci\u00e9t\u00e9 d'aujourd'hui promeut la conservation de l'\u00e9nergie et la r\u00e9duction des \u00e9missions. En tant que fabricant engag\u00e9 dans la production et la fabrication d'\u00e9quipements de s\u00e9chage depuis de nombreuses ann\u00e9es, nous nous effor\u00e7ons constamment de produire des \u00e9quipements de s\u00e9chage plus \u00e9conomes en \u00e9nergie et respectueux de l'environnement. Le co\u00fbt d'utilisation de l'appareil est r\u00e9duit, et les revenus sont pour nos utilisateurs. S\u00e8che-linge\u2026<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[2],"tags":[17],"class_list":["post-1047","post","type-post","status-publish","format-standard","hentry","category-events","tag-rotary-dryer"],"taxonomy_info":{"category":[{"value":2,"label":"News"}],"post_tag":[{"value":17,"label":"Rotary dryer"}]},"featured_image_src_large":false,"author_info":{"display_name":"Lolita","author_link":"https:\/\/www.charcoal-machines.com\/fr\/author\/admin"},"comment_info":0,"category_info":[{"term_id":2,"name":"News","slug":"events","term_group":0,"term_taxonomy_id":2,"taxonomy":"category","description":"","parent":0,"count":209,"filter":"raw","cat_ID":2,"category_count":209,"category_description":"","cat_name":"News","category_nicename":"events","category_parent":0}],"tag_info":[{"term_id":17,"name":"Rotary dryer","slug":"rotary-dryer","term_group":0,"term_taxonomy_id":17,"taxonomy":"post_tag","description":"","parent":0,"count":3,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/www.charcoal-machines.com\/fr\/wp-json\/wp\/v2\/posts\/1047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charcoal-machines.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charcoal-machines.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/fr\/wp-json\/wp\/v2\/comments?post=1047"}],"version-history":[{"count":0,"href":"https:\/\/www.charcoal-machines.com\/fr\/wp-json\/wp\/v2\/posts\/1047\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.charcoal-machines.com\/fr\/wp-json\/wp\/v2\/media?parent=1047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/fr\/wp-json\/wp\/v2\/categories?post=1047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/fr\/wp-json\/wp\/v2\/tags?post=1047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}