{"id":4607,"date":"2022-03-18T17:18:31","date_gmt":"2022-03-18T09:18:31","guid":{"rendered":"https:\/\/www.charcoal-machines.com\/?p=4607"},"modified":"2022-03-18T17:23:12","modified_gmt":"2022-03-18T09:23:12","slug":"charcoal-extruder-machine-shipped-to-the-uk","status":"publish","type":"post","link":"https:\/\/www.charcoal-machines.com\/es\/charcoal-extruder-machine-shipped-to-the-uk.html","title":{"rendered":"M\u00e1quina extrusora de carb\u00f3n enviada al Reino Unido"},"content":{"rendered":"<p class=\"wp-block-paragraph translation-block\">La extrusora de carb\u00f3n es una m\u00e1quina que puede convertir el carb\u00f3n en polvo en diferentes tiras. Es un tipo de <a href=\"https:\/\/www.charcoal-machines.com\/es\/biomass-sawdust-briquette-machine.html\">equipo para la formaci\u00f3n de varillas de carb\u00f3n<\/a>. Existen diferentes modelos de m\u00e1quinas formadoras de varillas de carb\u00f3n, que son adecuados para la producci\u00f3n individual y las f\u00e1bricas a gran escala para producir varillas de carb\u00f3n.<\/p>    <h2 class=\"wp-block-heading\">El proceso de cerrar un trato con un cliente de m\u00e1quina extrusora de carb\u00f3n.<\/h2>    <figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2022\/03\/coal-briquette-machine-.png\" alt=\" m\u00e1quina para briquetas de carb\u00f3n \" class=\"wp-image-4611\" srcset=\"https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2022\/03\/coal-briquette-machine-.png 720w, https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2022\/03\/coal-briquette-machine--300x225.png 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption> M\u00e1quina de Briquetas de Carb\u00f3n <\/figcaption><\/figure>    <p class=\"wp-block-paragraph\">Hemos recibido una consulta de un cliente sobre la m\u00e1quina extrusora de carb\u00f3n. El cliente es de Senegal. Aqu\u00ed, nos gustar\u00eda preguntar por qu\u00e9 el cliente senegal\u00e9s quiere enviar la m\u00e1quina de varillas de carb\u00f3n al Reino Unido. Despu\u00e9s de la conversaci\u00f3n, descubr\u00ed que el cliente actual est\u00e1 haciendo negocios en el Reino Unido, por lo que la m\u00e1quina necesita ser enviada al Reino Unido.<\/p>    <h3 class=\"wp-block-heading\">Entender la situaci\u00f3n de los clientes de la m\u00e1quina de briquetas de carb\u00f3n.<\/h3>    <p class=\"wp-block-paragraph\">Primero entendemos las necesidades de los clientes, la forma y el tipo de varillas de carb\u00f3n que queremos procesar, y solo cuando comprendemos la situaci\u00f3n de producci\u00f3n de los clientes en Senegal, podemos recomendar m\u00e1quinas adecuadas para varillas de carb\u00f3n. El cliente senegal\u00e9s es un fabricante local de varillas de carb\u00f3n. Ha estado dedicado a la producci\u00f3n de varillas de carb\u00f3n durante varios a\u00f1os, pero la producci\u00f3n no es muy grande. Creo que es m\u00e1s optimista sobre la industria de producci\u00f3n y procesamiento de varillas de carb\u00f3n. Por lo tanto, queremos comprar una m\u00e1quina extrusora de carb\u00f3n vegetal para aumentar la producci\u00f3n. Queremos que el cliente env\u00ede los modelos de varias m\u00e1quinas de varillas de carb\u00f3n que actualmente produce la f\u00e1brica. La m\u00e1quina con la producci\u00f3n m\u00ednima es de 500 kg\/h, y la m\u00e1quina con la producci\u00f3n m\u00e1xima es de 3000 kg\/h. Enviaremos la informaci\u00f3n ordenada al cliente para su selecci\u00f3n.<\/p>    <figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2022\/03\/Charcoal-coal-stick-machine-mould.png\" alt=\"Molde de m\u00e1quina de palos de carb\u00f3n de le\u00f1a\" class=\"wp-image-4612\" srcset=\"https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2022\/03\/Charcoal-coal-stick-machine-mould.png 720w, https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2022\/03\/Charcoal-coal-stick-machine-mould-300x225.png 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption>Molde para m\u00e1quina de palos de carb\u00f3n<\/figcaption><\/figure>    <h3 class=\"wp-block-heading\">Presentar el modelo de la m\u00e1quina extrusora de carb\u00f3n de la empresa Shuliy.<\/h3>    <p class=\"wp-block-paragraph\">El cliente dijo que tiene que trabajar durante el d\u00eda, por lo que le resulta lento responder al mensaje cada vez, y lo entendemos muy bien. El cliente dijo que la industria de procesamiento de varillas de carb\u00f3n todav\u00eda se lleva a cabo todos los d\u00edas. Al principio de la conversaci\u00f3n, el cliente quer\u00eda comprar una m\u00e1quina modelo 180, pero no necesitaba cortador ni transportador. El cliente planeaba cortarlo a mano, pero el problema del corte manual es que las longitudes de las varillas de carb\u00f3n cortadas son diferentes, lo que es muy poco est\u00e9tico. Entendemos que los clientes quieren ahorrar costos, pero esto no es beneficioso para la producci\u00f3n a largo plazo.<\/p>    <figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2022\/03\/Charcoal.png\" alt=\"Carb\u00f3n vegetal\" class=\"wp-image-4616\" srcset=\"https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2022\/03\/Charcoal.png 720w, https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2022\/03\/Charcoal-300x225.png 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption>Carb\u00f3n vegetal<\/figcaption><\/figure>    <h3 class=\"wp-block-heading\">Firmado un contrato con un cliente de m\u00e1quina extrusora de carb\u00f3n.<\/h3>    <p class=\"wp-block-paragraph\">Despu\u00e9s del an\u00e1lisis, seguimos recomendando una m\u00e1quina con bajo rendimiento pero con funci\u00f3n de corte a los clientes. Enviamos fotos de la m\u00e1quina y videos de trabajo, y el cliente pregunt\u00f3 sobre el tiempo de entrega. Nuestra f\u00e1brica tiene productos semiterminados de la m\u00e1quina, y luego se puede enviar dentro de 3-5 d\u00edas despu\u00e9s de firmar el contrato con el cliente, y se adjuntar\u00e1 el certificado CE.<\/p>    <figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2022\/03\/Charcoal-extruder-machine-1.png\" alt=\"M\u00e1quina extrusora de carb\u00f3n\" class=\"wp-image-4613\" srcset=\"https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2022\/03\/Charcoal-extruder-machine-1.png 720w, https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2022\/03\/Charcoal-extruder-machine-1-300x225.png 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption>M\u00e1quina Extrusora de Carb\u00f3n<\/figcaption><\/figure>    <h2 class=\"wp-block-heading\" id=\"h-charcoal-extruder-machine-model\">modelo de m\u00e1quina extrusora de carb\u00f3n<\/h2>    <figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2022\/03\/Charcoal-extruder-machine-model.png\" alt=\"modelo de m\u00e1quina extrusora de carb\u00f3n\" class=\"wp-image-4614\" srcset=\"https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2022\/03\/Charcoal-extruder-machine-model.png 720w, https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2022\/03\/Charcoal-extruder-machine-model-300x225.png 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption>Modelo de m\u00e1quina extrusora de carb\u00f3n<\/figcaption><\/figure>    <figure class=\"wp-block-table\"><table><tbody><tr><td>Modelo <br>Nombre  \u00a0<\/td><td> MBJ140 <\/td><td> MBJ180 <\/td><td> MBJ210 <\/td><td> MBJ300 <\/td><td> MBJ400 <\/td><\/tr><tr><td>capacidad de producci\u00f3n<\/td><td> 500kg\/h <\/td><td> 1000kg\/h <\/td><td> 1500kg\/h <\/td><td> 2000kg\/h <\/td><td> 3000kg\/h <\/td><\/tr><tr><td>Especificaciones de formaci\u00f3n<\/td><td>Di\u00e1metro 20-40<\/td><td>Di\u00e1metro 20-60<\/td><td>Di\u00e1metro 20-80<\/td><td>Di\u00e1metro 20-80<\/td><td>Di\u00e1metro 20-80<\/td><\/tr><tr><td>Velocidad del husillo<\/td><td>46-60 rpm<\/td><td>39-60 rpm<\/td><td>35-60 rpm<\/td><td>35-60 rpm<\/td><td>35-60 rpm<\/td><\/tr><tr><td>N\u00famero de cuchillas helicoidales<\/td><td>4<\/td><td>4<\/td><td>4<\/td><td>4<\/td><td>4<\/td><\/tr><tr><td>motor<\/td><td> Y160m-4 11kw <\/td><td> Y180m-4 18.5kw <\/td><td> Y200L-4 30kw <\/td><td> Y225s-4 37kw <\/td><td> Y315m-4 160kw <\/td><\/tr><tr><td>reductor<\/td><td> ZQ350 <\/td><td> ZQ400 <\/td><td> ZQ500 <\/td><td> ZQ650-750 <\/td><td> ZQ850 <\/td><\/tr><tr><td>cojinete<\/td><td> \u00a07511, 211, 210, 1305 <\/td><td> 7614, 314, 313, 1206 <\/td><td> 7619, 319, 318, 1206 <\/td><td> 32320, 320, 319, 1207 <\/td><td> 32322, 322, 321 <\/td><\/tr><\/tbody><\/table><figcaption>M\u00e1quina extrusora de carb\u00f3n<\/figcaption><\/figure>    <h2 class=\"wp-block-heading\">\u00bfPor qu\u00e9 los clientes eligen Shuliy?<\/h2>    <figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2022\/03\/48-637x1024.jpg\" alt=\"\" class=\"wp-image-4615\" width=\"687\" height=\"836\"><\/figure>    <p class=\"wp-block-paragraph\">1. El certificado est\u00e1 completo. Se requiere un certificado CE cuando la m\u00e1quina se env\u00eda al puerto del Reino Unido, Schulley puede proporcionar un certificado profesional.<\/p>    <p class=\"wp-block-paragraph\">2. Enviar informaci\u00f3n a tiempo. Los clientes suelen tener horarios de trabajo ocupados, y no hay mucho tiempo para la comunicaci\u00f3n. Resolvemos las preguntas de los clientes de manera oportuna cada vez y enviamos la informaci\u00f3n de la m\u00e1quina de varillas de carb\u00f3n que requieren los clientes.<\/p>    <p class=\"wp-block-paragraph\">3. La m\u00e1quina es de buena calidad y modelos completos. Ofrecemos m\u00e1quinas que satisfacen las necesidades del cliente.<\/p>   <div class=\"kk-star-ratings kksr-auto kksr-align-right kksr-valign-bottom\"     data-payload='{&quot;align&quot;:&quot;right&quot;,&quot;id&quot;:&quot;4607&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;16&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.7&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.7\\\/5 - (16 votos)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Charcoal extruder machine shipped to the UK&quot;,&quot;width&quot;:&quot;129.6&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>              <div class=\"kksr-stars\">      <div class=\"kksr-stars-inactive\">             <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div>      <div class=\"kksr-stars-active\" style=\"width: 129.6px;\">             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div> <\/div>                   <div class=\"kksr-legend\" style=\"font-size: 19.2px;\">             4.7\/5 - (16 votos)    <\/div>     <\/div>","protected":false},"excerpt":{"rendered":"<p>La m\u00e1quina extrusora de carb\u00f3n es una m\u00e1quina que puede convertir el carb\u00f3n en polvo en diferentes tiras. Es un tipo de equipo para la formaci\u00f3n de varillas de carb\u00f3n. Hay diferentes modelos de m\u00e1quinas para la formaci\u00f3n de varillas de carb\u00f3n, que son adecuadas para la producci\u00f3n individual y f\u00e1bricas a gran escala para producir varillas de carb\u00f3n.<\/p>","protected":false},"author":1,"featured_media":4610,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1941],"tags":[1948],"class_list":["post-4607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sucessfulcases","tag-charcoal-extruder-machine"],"taxonomy_info":{"category":[{"value":1941,"label":"Sucessful cases"}],"post_tag":[{"value":1948,"label":"Charcoal extruder machine"}]},"featured_image_src_large":["https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2022\/03\/Charcoal-extruder-machine.png",720,540,false],"author_info":{"display_name":"Lolita","author_link":"https:\/\/www.charcoal-machines.com\/es\/author\/admin"},"comment_info":0,"category_info":[{"term_id":1941,"name":"Sucessful cases","slug":"sucessfulcases","term_group":0,"term_taxonomy_id":1941,"taxonomy":"category","description":"","parent":0,"count":82,"filter":"raw","cat_ID":1941,"category_count":82,"category_description":"","cat_name":"Sucessful cases","category_nicename":"sucessfulcases","category_parent":0}],"tag_info":[{"term_id":1948,"name":"Charcoal extruder machine","slug":"charcoal-extruder-machine","term_group":0,"term_taxonomy_id":1948,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/www.charcoal-machines.com\/es\/wp-json\/wp\/v2\/posts\/4607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charcoal-machines.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charcoal-machines.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/es\/wp-json\/wp\/v2\/comments?post=4607"}],"version-history":[{"count":0,"href":"https:\/\/www.charcoal-machines.com\/es\/wp-json\/wp\/v2\/posts\/4607\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/es\/wp-json\/wp\/v2\/media\/4610"}],"wp:attachment":[{"href":"https:\/\/www.charcoal-machines.com\/es\/wp-json\/wp\/v2\/media?parent=4607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/es\/wp-json\/wp\/v2\/categories?post=4607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/es\/wp-json\/wp\/v2\/tags?post=4607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}