{"id":983,"date":"2018-11-05T01:52:10","date_gmt":"2018-11-05T01:52:10","guid":{"rendered":"http:\/\/www.charcoal-machines.com\/?p=983"},"modified":"2019-05-27T07:29:39","modified_gmt":"2019-05-27T07:29:39","slug":"mechanism-charcoal-burns-longer-than-log-carbon","status":"publish","type":"post","link":"https:\/\/www.charcoal-machines.com\/de\/mechanism-charcoal-burns-longer-than-log-carbon.html","title":{"rendered":"Maschinengefertigte Kohle brennt l\u00e4nger als Holz-Kohle"},"content":{"rendered":"<p>Wenn man die Produktqualit\u00e4t des maschinell hergestellten Holzkohlen mit der traditionellen Stammholzkohle vergleicht, hat die hochdruckgepresste Holzkohle den Vorteil einer h\u00f6heren Dichte des fertigen Kohlenprodukts. F\u00fcr die Brennwirkung der Holzkohle bei der Verwendung hat die maschinell hergestellte Holzkohle eine gro\u00dfe Dichte, die unter dem Mikroskop sichtbar wird.<\/p> <p>Je niedriger die kapillare Porosit\u00e4t, desto l\u00e4nger ist die Brenndauer der Holzkohle im Vergleich zum gleichen Gewicht, die maschinell hergestellte Holzkohle hat die Vorteile eines hohen Kohlenstoffgehalts, eines hohen Heizwerts, einer geringen Fl\u00fcchtigkeit und einer langen Brenndauer. Sie ist 2-4 Mal so lange wie gew\u00f6hnliche Rohholzkohle und ist rauch- und geschmacklos, weshalb sie von Nutzern im In- und Ausland gesch\u00e4tzt wird. Die Technologie der maschinell hergestellten Holzkohle ist auch f\u00fcr die Massen leicht zu erlernen.<\/p> <div class=\"col-md-6\"><img loading=\"lazy\" decoding=\"async\" width=\"278\" height=\"195\" class=\"alignnone size-full wp-image-984\" src=\"http:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2018\/11\/charcoal-machine-production-line.jpg\" alt=\"Holzkohlemaschinenproduktionslinie\" \/><\/div> <div class=\"col-md-6\"><img loading=\"lazy\" decoding=\"async\" width=\"278\" height=\"195\" class=\"alignnone size-full wp-image-985\" src=\"http:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2018\/11\/charcoal-machine-production-line1.jpg\" alt=\"Holzkohlemaschinenproduktionslinie\" \/><\/div> <p class=\"translation-block\">Die <a href=\"https:\/\/www.charcoal-machines.com\/de\/\"><strong>Kohlemaschinen-Produktionslinie<\/strong><\/a> hat niedrige Investitionen und geringe Kosten, die von 70.000 bis 80.000 und bis zu 100.000 reichen. Im Fall von allem, nur der Ostwind, ist die Kohlemaschine die oberste Priorit\u00e4t.<\/p> <p>Die derzeit verwendeten Brennstoffe wie \u00d6l, Erdgas und Kohle sind nicht erneuerbare Energiequellen. Die verschiedenen Eigenschaften dieser Ressourcen veranlassten die FAO, Anfang 1971 zu erkennen, dass die praktischste Nutzung von Reish\u00fclsen in der absehbaren Zukunft darin besteht, Energie in Form von Brennstoff bereitzustellen.<\/p> <p>Hersteller von Holzkohlemaschinen analysieren die geeignete Stabtemperatur der Holzkohlemaschinenausr\u00fcstung, was ein guter Faktor f\u00fcr die Produktion ist. Reish\u00fclsen werden seit \u00fcber 100 Jahren als Brennstoff in Reisfabriken verwendet, um W\u00e4rme oder Energie bereitzustellen. Der erste Nachweis, dass Reish\u00fclsen als Energiequelle verwendet werden, war ein Reislichtbrennofen, der 1889 in Myanmar gebaut wurde. Diese Anwendung hat keinen kommerziellen Status erreicht, was haupts\u00e4chlich durch ung\u00fcnstige Faktoren wie das gro\u00dfe Volumen der Reish\u00fclsen und Schwierigkeiten bei der instabilen Versorgung eingeschr\u00e4nkt wird.<\/p>   <div class=\"kk-star-ratings kksr-auto kksr-align-right kksr-valign-bottom\"     data-payload='{&quot;align&quot;:&quot;right&quot;,&quot;id&quot;:&quot;983&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;6&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.8&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.8\\\/5 - (6 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Machine-made charcoal burns longer than log carbon&quot;,&quot;width&quot;:&quot;132.4&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>              <div class=\"kksr-stars\">      <div class=\"kksr-stars-inactive\">             <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div>      <div class=\"kksr-stars-active\" style=\"width: 132.4px;\">             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div> <\/div>                   <div class=\"kksr-legend\" style=\"font-size: 19.2px;\">             4,8\/5 - (6 Stimmen)    <\/div>     <\/div>","protected":false},"excerpt":{"rendered":"<p>Wenn man den Qualit\u00e4tseffekt des maschinell hergestellten Holzkohlenprodukts mit der traditionellen Holzscheitkohle vergleicht, hat die hochdruckgepresste Holzkohle den Vorteil einer h\u00f6heren Dichte des fertigen Kohlenprodukts. F\u00fcr die Brennwirkung der Holzkohle bei der Verwendung ist die Dichte der maschinell hergestellten Holzkohle hoch, und sie wird unter dem Mikroskop dargestellt. Die niedrigere...<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[2],"tags":[34],"class_list":["post-983","post","type-post","status-publish","format-standard","hentry","category-events","tag-charcoal-machine-production-line"],"taxonomy_info":{"category":[{"value":2,"label":"News"}],"post_tag":[{"value":34,"label":"charcoal machine production line"}]},"featured_image_src_large":false,"author_info":{"display_name":"Lolita","author_link":"https:\/\/www.charcoal-machines.com\/de\/author\/admin"},"comment_info":0,"category_info":[{"term_id":2,"name":"News","slug":"events","term_group":0,"term_taxonomy_id":2,"taxonomy":"category","description":"","parent":0,"count":209,"filter":"raw","cat_ID":2,"category_count":209,"category_description":"","cat_name":"News","category_nicename":"events","category_parent":0}],"tag_info":[{"term_id":34,"name":"charcoal machine production line","slug":"charcoal-machine-production-line","term_group":0,"term_taxonomy_id":34,"taxonomy":"post_tag","description":"","parent":0,"count":9,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/posts\/983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/comments?post=983"}],"version-history":[{"count":0,"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/posts\/983\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/media?parent=983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/categories?post=983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/tags?post=983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}