{"id":922,"date":"2018-10-23T03:23:11","date_gmt":"2018-10-23T03:23:11","guid":{"rendered":"http:\/\/www.charcoal-machines.com\/?p=922"},"modified":"2019-05-27T08:04:38","modified_gmt":"2019-05-27T08:04:38","slug":"the-correct-use-of-carbonization-furnace","status":"publish","type":"post","link":"https:\/\/www.charcoal-machines.com\/de\/the-correct-use-of-carbonization-furnace.html","title":{"rendered":"Die korrekte Verwendung des Karbonisierungsofens"},"content":{"rendered":"<p class=\"translation-block\">Der \u201eKarbonisierungsprozess\u201c in der <a href=\"https:\/\/www.charcoal-machines.com\/de\/charcoal-briquette-production-line\/\"><strong>Brikettproduktionsanlage f\u00fcr Holzkohle<\/strong><\/a> ist ein wichtiger Teil des gesamten Holzkohleproduktionsprozesses. Der Brennstoffriegel (Halbfertigprodukt) bestimmt direkt die Produkteigenschaften und den Marktpreis der mechanischen Holzkohle nach dem Karbonisierungsprozess. Wie also die <a href=\"http:\/\/www.charcoal-machines.com\/de\/continuous-carbonization-furnace.html\"><strong>Karbonisierungsofen<\/strong><\/a>-Ausr\u00fcstung sinnvoll und sicher betrieben wird, erkl\u00e4ren wir den Benutzern nun.<\/p> <p class=\"translation-block\">Die Gefahr von Gaslecks bei der Verwendung eines Karbonisierungsofens und vorbeugende Ma\u00dfnahmen: Der <strong>Karbonisierungsofen<\/strong> muss dicht verschlossen sein. Sobald Luft eindringt, kann die Menge des in den Ofen eintretenden Sauerstoffs nicht kontrolliert werden. Der Brennstoffriegel im Ofen entz\u00fcndet sich leicht \u00fcberm\u00e4\u00dfig selbst und karbonisiert. Die Temperatur steigt zu schnell an, sodass die gebrannte Holzkohle locker und leicht zerbrechlich ist. Schlimmer noch, \u00fcbersch\u00fcssiger Sauerstoff verbrennt einige der Brennstoffriegel zu einem wei\u00dfen Pulver (Asche), was zu einer Verringerung der Holzkohleproduktion f\u00fchrt. Daher sollten der Betrieb und die Ofenverpackung gem\u00e4\u00df unseren Anweisungen durchgef\u00fchrt werden.<\/p> <div class=\"row\"> <div class=\"col-md-6\"> <div id='gallery-1' class='gallery galleryid-922 gallery-columns-2 gallery-size-full'><figure class='gallery-item'> \t\t\t<div class='gallery-icon landscape'> \t\t\t\t<a href='https:\/\/www.charcoal-machines.com\/de\/carbonization-furnace8'><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2018\/08\/carbonization-furnace8.jpg\" class=\"attachment-full size-full\" alt=\"Kohlenstoffisierungsofen\" srcset=\"https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2018\/08\/carbonization-furnace8.jpg 600w, https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2018\/08\/carbonization-furnace8-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a> \t\t\t<\/div><\/figure><figure class='gallery-item'> \t\t\t<div class='gallery-icon landscape'> \t\t\t\t<a href='https:\/\/www.charcoal-machines.com\/de\/carbonization-furnace6'><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2018\/08\/carbonization-furnace6.jpg\" class=\"attachment-full size-full\" alt=\"Kohlenstoffisierungsofen\" srcset=\"https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2018\/08\/carbonization-furnace6.jpg 600w, https:\/\/www.charcoal-machines.com\/wp-content\/uploads\/2018\/08\/carbonization-furnace6-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a> \t\t\t<\/div><\/figure> \t\t<\/div>  <\/div> <div class=\"col-md-6\"><\/div> <\/div> <p>Im Karbonisierungsprozess wird der Karbonisierungsprozess in drei Phasen unterteilt:<\/p> <p>Niedertemperatur-Entladungstemperatur, Hochtemperatur-Calcination und K\u00fchlung. Der Gehaltsbalken hat etwa 8% Wasser, wenn er in den Karbonisierungsofen eintritt. Dieses Wasser ist der Feind der Karbonisierung. Denn der mechanische Gehaltsbalken hat am meisten Angst vor Feuchtigkeit, das Wasser wird die Qualit\u00e4t der Karbonisierung im Gehaltsbalken ernsthaft beeintr\u00e4chtigen, daher ist die Zeit des Entw\u00e4sserns entscheidend. Die Entw\u00e4sserung dauert in der Regel 10-15 Stunden f\u00fcr den Erdkessel und 2-3,5 Stunden f\u00fcr den mechanischen Ofen.<\/p> <p>Die Heizzeit ist lang, was verhindern kann, dass die Gehaltsstange durch Feuchtigkeit rissig wird und die Qualit\u00e4t der Karbonisierung sichergestellt wird. Wenn die Ofentemperatur auf 300 Grad steigt, kann eine gro\u00dfe Menge brennbares Gas im Ofen erzeugt werden. Diese Gase k\u00f6nnen verwendet werden, um den Ofen zu heizen. Die Abw\u00e4rmequelle f\u00fcr die Trocknung \u00fcber 400 Grad f\u00fcr die W\u00e4rmeisolierung und Kalzinierung kann durch Selbstentz\u00fcndungsk\u00fchlung oder Wasserk\u00fchlung erhalten werden, um das sauerstofffreie geschlossene Feuer abzudichten.<\/p> <p>Nach dem Ende des Karbonisierungsprozesses ist es dem Benutzer untersagt, den Holzkohleprozess unter der Voraussetzung der Kohlenstoffentfernung oder hohen Temperaturen durchzuf\u00fchren. Der Holzkohlesammelvorgang kann unter der Voraussetzung durchgef\u00fchrt werden, dass die Bel\u00fcftung des Ofenk\u00f6rpers stabil und geeignet ist. Nach der Sammlung ist es untersagt, die Holzkohle zu chargieren. Das Stapeln im Lager muss innerhalb von acht Stunden nach der Entladung des Ofens im Luftk\u00fchl- und Flammenl\u00f6schbetrieb erfolgen, um Br\u00e4nde durch die innere Verbrennung der Holzkohle nach der Freigabe des Mechanismus zu vermeiden.<\/p>   <div class=\"kk-star-ratings kksr-auto kksr-align-right kksr-valign-bottom\"     data-payload='{&quot;align&quot;:&quot;right&quot;,&quot;id&quot;:&quot;922&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;27&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.7&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.7\\\/5 - (27 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;The correct use of carbonization furnace&quot;,&quot;width&quot;:&quot;129.6&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>              <div class=\"kksr-stars\">      <div class=\"kksr-stars-inactive\">             <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div>      <div class=\"kksr-stars-active\" style=\"width: 129.6px;\">             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 4px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div> <\/div>                   <div class=\"kksr-legend\" style=\"font-size: 19.2px;\">             4,7\/5 - (27 Stimmen)    <\/div>     <\/div>","protected":false},"excerpt":{"rendered":"<p>Der \"Karbonisierungs\"-Prozess in der Produktionslinie f\u00fcr Holzkohlebriketts ist ein wichtiger Teil des gesamten Kohlenstoffproduktionsprozesses. Der Brennstoffstab (Halbfertigprodukt) bestimmt direkt die Produkteigenschaften und den Marktpreis der mechanischen Holzkohle nach dem Karbonisierungsprozess. Wie man die Karbonisierungs\u00f6fen angemessen und sicher betreibt, wird nun erkl\u00e4rt\u2026<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[2],"tags":[9,35],"class_list":["post-922","post","type-post","status-publish","format-standard","hentry","category-events","tag-carbonization-furnace","tag-charcoal-briquette-production-line"],"taxonomy_info":{"category":[{"value":2,"label":"News"}],"post_tag":[{"value":9,"label":"carbonization furnace"},{"value":35,"label":"charcoal briquette production line"}]},"featured_image_src_large":false,"author_info":{"display_name":"Lolita","author_link":"https:\/\/www.charcoal-machines.com\/de\/author\/admin"},"comment_info":0,"category_info":[{"term_id":2,"name":"News","slug":"events","term_group":0,"term_taxonomy_id":2,"taxonomy":"category","description":"","parent":0,"count":209,"filter":"raw","cat_ID":2,"category_count":209,"category_description":"","cat_name":"News","category_nicename":"events","category_parent":0}],"tag_info":[{"term_id":9,"name":"carbonization furnace","slug":"carbonization-furnace","term_group":0,"term_taxonomy_id":9,"taxonomy":"post_tag","description":"","parent":0,"count":23,"filter":"raw"},{"term_id":35,"name":"charcoal briquette production line","slug":"charcoal-briquette-production-line","term_group":0,"term_taxonomy_id":35,"taxonomy":"post_tag","description":"","parent":0,"count":12,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/posts\/922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/comments?post=922"}],"version-history":[{"count":0,"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/posts\/922\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/media?parent=922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/categories?post=922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charcoal-machines.com\/de\/wp-json\/wp\/v2\/tags?post=922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}